{"id":1359,"date":"2018-11-01T08:04:50","date_gmt":"2018-11-01T14:04:50","guid":{"rendered":"http:\/\/ranchonatura.com\/?p=1810"},"modified":"2018-10-31T16:51:16","modified_gmt":"2018-10-31T22:51:16","slug":"fitball","status":"publish","type":"post","link":"https:\/\/aguida.com\/en\/fitball\/","title":{"rendered":"FITBALL"},"content":{"rendered":"<p>El fitball es una actividad de las consideradas suaves, pero que ayuda a entrenar el cuerpo de forma completa e incluso a rehabilitar determinadas lesiones.<\/p>\n<p>Esta es una pr\u00e1ctica deportiva que, desde los a\u00f1os 60, va sumando, d\u00eda a d\u00eda, nuevos adeptos. Naci\u00f3 como una actividad de rehabilitaci\u00f3n, luego se fue incorporando a los gimnasios. Ahora est\u00e1 tan extendida la utilizaci\u00f3n de las fitballs que incluso ya hay oficinas que han sustituido las tradicionales sillas por estas bolas gigantes para cuidar la espalda de todos sus empleados.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-1811 aligncenter\" src=\"http:\/\/aguida.com\/wp-content\/uploads\/2018\/10\/Ejercita-abdominales-con-fitball-300x199.jpg\" alt=\"\" width=\"704\" height=\"467\" \/><\/p>\n<p>Los principales\u00a0<strong>beneficios del fitball son los siguientes<\/strong>:<\/p>\n<ul>\n<li>El fitball es gimnasia suave que, sin embargo, permite trabajar todo el cuerpo de forma completa.<\/li>\n<li>Mejora el equilibrio y la propiocepci\u00f3n, esto es, el sentido que permite saber cu\u00e1l es la posici\u00f3n relativa de los diferentes m\u00fasculos a lo largo de todo el organismo.<\/li>\n<li>Aunque con las fitballs se pueden entrenar muchas zonas del cuerpo, su trabajo principal se realiza en el denominado \u2018core\u2019 (la parte media del cuerpo donde se encuentra el transverso abdominal, suelo p\u00e9lvico y\u00a0gl\u00fateos) y en los estabilizadores de la columna.<\/li>\n<li>Mejor control postural, puesto que se fortalecen los m\u00fasculos y, con ello, la capacidad de una mayor estabilidad del cuerpo.<\/li>\n<li>La superficie y la relativa dureza de las fitballs hace que se adapte a las diferentes caracter\u00edsticas de las personas que las usan.<\/li>\n<li>Las bolas gigantes ofrecen un acondicionamiento f\u00edsico integral, ya que, con ellas, se trabaja tanto la coordinaci\u00f3n y la flexibilidad como la resistencia y la fuerza.<\/li>\n<li>Las fitballs tambi\u00e9n se utilizan como complemento en clases de actividades aer\u00f3bicas, por lo que es una herramienta m\u00e1s para hacer trabajar el\u00a0sistema cardiovascular. Se pueden incluir tanto en la fase de\u00a0calentamiento\u00a0como en la de ejercicios y, por supuesto, en la parte final de estiramientos.<\/li>\n<\/ul>\n<p>Hay una serie de pautas que deben seguir las personas que practiquen\u00a0<strong>fitball<\/strong>, ya sea como una herramienta de acondicionamiento f\u00edsico, o como un elemento de ayuda en la rehabilitaci\u00f3n de alguna lesi\u00f3n.<\/p>\n<p>Adem\u00e1s, es importante determinar cu\u00e1l es el objetivo de este entrenamiento, puesto que no ser\u00e1n los mismos ejercicios, cargas y repeticiones, esto depende de lo que queramos lograr al realizar esta pr\u00e1ctica.<\/p>\n<ul>\n<li>Para limpiarlas, basta con lavar las pelotas con un trapo mojado. Si es necesario, se puede utilizar jab\u00f3n, pero sin frotar con fibras u otro material abrasivo.<\/li>\n<li>Como en cualquier actividad f\u00edsica, debes calentar antes de empezar los ejercicios y no te olvides de estirar cuando termines para evitar lesiones.<\/li>\n<li>Una correcta\u00a0hidrataci\u00f3n\u00a0es muy importante antes, durante y despu\u00e9s de la tabla de ejercicios de fitball.<\/li>\n<\/ul>\n<p>Te compartimos un video de una clase de fitball para que te animes a hacerla.<\/p>\n<div class=\"ast-oembed-container\" style=\"height: 100%;\"><iframe loading=\"lazy\" title=\"G.A.P. express - Gl\u00fateos Abdomen Piernas con FIT BALL en 10 min | D\u00eda 3\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/U9pP0IBUGSs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El fitball es una actividad de las consideradas suaves, pero que ayuda a entrenar el cuerpo de forma completa e incluso a rehabilitar determinadas lesiones. Esta es una pr\u00e1ctica deportiva que, desde los a\u00f1os 60, va sumando, d\u00eda a d\u00eda, nuevos adeptos. Naci\u00f3 como una actividad de rehabilitaci\u00f3n, luego se fue incorporando a los gimnasios. &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/aguida.com\/en\/fitball\/\"> <span class=\"screen-reader-text\">FITBALL<\/span> Read More &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":1370,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"categories":[7,3],"tags":[],"class_list":["post-1359","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eng","category-esp"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/aguida.com\/en\/wp-json\/wp\/v2\/posts\/1359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aguida.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aguida.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aguida.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aguida.com\/en\/wp-json\/wp\/v2\/comments?post=1359"}],"version-history":[{"count":4,"href":"https:\/\/aguida.com\/en\/wp-json\/wp\/v2\/posts\/1359\/revisions"}],"predecessor-version":[{"id":1369,"href":"https:\/\/aguida.com\/en\/wp-json\/wp\/v2\/posts\/1359\/revisions\/1369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aguida.com\/en\/wp-json\/wp\/v2\/media\/1370"}],"wp:attachment":[{"href":"https:\/\/aguida.com\/en\/wp-json\/wp\/v2\/media?parent=1359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aguida.com\/en\/wp-json\/wp\/v2\/categories?post=1359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aguida.com\/en\/wp-json\/wp\/v2\/tags?post=1359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}